{"id":841,"date":"2020-12-16T15:01:38","date_gmt":"2020-12-16T18:01:38","guid":{"rendered":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg"},"modified":"2020-12-16T15:01:38","modified_gmt":"2020-12-16T18:01:38","slug":"banner-colheita-milho","status":"inherit","type":"attachment","link":"https:\/\/sementesbiomatrix.com.br\/blog\/produtividade\/colheita-do-milho\/attachment\/banner-colheita-milho\/","title":{"rendered":"banner-colheita-milho"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"tdm_status":"","tdm_grid_status":""},"class_list":["post-841","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>banner-colheita-milho - Biomatrix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"banner-colheita-milho - Biomatrix\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Biomatrix\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/banner-colheita-milho.jpg\",\"url\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/banner-colheita-milho.jpg\",\"name\":\"banner-colheita-milho - Biomatrix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2020-12-16T18:01:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/banner-colheita-milho.jpg#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/banner-colheita-milho.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/banner-colheita-milho.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colheita de milho: pontos para melhorar sua safra\",\"item\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/produtividade\\\/colheita-do-milho\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"banner-colheita-milho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/\",\"name\":\"Biomatrix\",\"description\":\"Biomatrix\",\"publisher\":{\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#organization\",\"name\":\"Sementes Biomatrix\",\"url\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-4.png\",\"contentUrl\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo-4.png\",\"width\":150,\"height\":35,\"caption\":\"Sementes Biomatrix\"},\"image\":{\"@id\":\"https:\\\/\\\/sementesbiomatrix.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"banner-colheita-milho - Biomatrix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","og_locale":"pt_BR","og_type":"article","og_title":"banner-colheita-milho - Biomatrix","og_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","og_site_name":"Biomatrix","og_image":[{"width":900,"height":180,"url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","name":"banner-colheita-milho - Biomatrix","isPartOf":{"@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#website"},"datePublished":"2020-12-16T18:01:38+00:00","breadcrumb":{"@id":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sementesbiomatrix.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Colheita de milho: pontos para melhorar sua safra","item":"https:\/\/sementesbiomatrix.com.br\/blog\/produtividade\/colheita-do-milho\/"},{"@type":"ListItem","position":3,"name":"banner-colheita-milho"}]},{"@type":"WebSite","@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#website","url":"https:\/\/sementesbiomatrix.com.br\/blog\/","name":"Biomatrix","description":"Biomatrix","publisher":{"@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sementesbiomatrix.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#organization","name":"Sementes Biomatrix","url":"https:\/\/sementesbiomatrix.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/09\/logo-4.png","contentUrl":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/09\/logo-4.png","width":150,"height":35,"caption":"Sementes Biomatrix"},"image":{"@id":"https:\/\/sementesbiomatrix.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"smush":{"stats":{"percent":7.103047244366222,"bytes":16466,"size_before":231816,"size_after":215350,"time":0.7400000000000002,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":5.65,"bytes":351,"size_before":6215,"size_after":5864,"time":0.02},"thumbnail":{"percent":9.1,"bytes":280,"size_before":3076,"size_after":2796,"time":0.03},"medium_large":{"percent":7.15,"bytes":1618,"size_before":22614,"size_after":20996,"time":0.01},"td_218x150":{"percent":7.09,"bytes":384,"size_before":5418,"size_after":5034,"time":0.31},"td_324x400":{"percent":8.7,"bytes":927,"size_before":10654,"size_after":9727,"time":0.01},"td_485x360":{"percent":8.2,"bytes":1364,"size_before":16626,"size_after":15262,"time":0.02},"td_696x0":{"percent":6.47,"bytes":1269,"size_before":19620,"size_after":18351,"time":0.02},"td_80x60":{"percent":7.21,"bytes":134,"size_before":1858,"size_after":1724,"time":0.01},"td_100x70":{"percent":6.59,"bytes":150,"size_before":2277,"size_after":2127,"time":0.1},"td_265x198":{"percent":8.59,"bytes":705,"size_before":8207,"size_after":7502,"time":0.03},"td_324x160":{"percent":6.86,"bytes":638,"size_before":9304,"size_after":8666,"time":0.01},"td_324x235":{"percent":0,"bytes":0,"size_before":9727,"size_after":9727,"time":0.04},"td_356x220":{"percent":8.32,"bytes":991,"size_before":11917,"size_after":10926,"time":0.02},"td_356x364":{"percent":0,"bytes":0,"size_before":10926,"size_after":10926,"time":0.05},"td_533x261":{"percent":8.19,"bytes":1559,"size_before":19035,"size_after":17476,"time":0.01},"td_534x462":{"percent":8.26,"bytes":1572,"size_before":19041,"size_after":17469,"time":0.01},"td_696x385":{"percent":8.14,"bytes":2186,"size_before":26849,"size_after":24663,"time":0.02},"td_741x486":{"percent":8.22,"bytes":2338,"size_before":28452,"size_after":26114,"time":0.02}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg'><img decoding=\"async\" width=\"300\" height=\"60\" src=\"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-300x60.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-300x60.jpg 300w, https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-768x154.jpg 768w, https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-696x139.jpg 696w, https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div style=\"min-height: 30px;display: inline-block;\"><\/div>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":900,"height":180,"file":"2020\/12\/banner-colheita-milho.jpg","sizes":{"medium":{"file":"banner-colheita-milho-300x60.jpg","width":300,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-300x60.jpg"},"thumbnail":{"file":"banner-colheita-milho-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-150x150.jpg"},"medium_large":{"file":"banner-colheita-milho-768x154.jpg","width":768,"height":154,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-768x154.jpg"},"td_218x150":{"file":"banner-colheita-milho-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-218x150.jpg"},"td_324x400":{"file":"banner-colheita-milho-324x180.jpg","width":324,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-324x180.jpg"},"td_485x360":{"file":"banner-colheita-milho-485x180.jpg","width":485,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-485x180.jpg"},"td_696x0":{"file":"banner-colheita-milho-696x139.jpg","width":696,"height":139,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-696x139.jpg"},"td_80x60":{"file":"banner-colheita-milho-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-80x60.jpg"},"td_100x70":{"file":"banner-colheita-milho-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-100x70.jpg"},"td_265x198":{"file":"banner-colheita-milho-265x180.jpg","width":265,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-265x180.jpg"},"td_324x160":{"file":"banner-colheita-milho-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-324x160.jpg"},"td_324x235":{"file":"banner-colheita-milho-324x180.jpg","width":324,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-324x180.jpg"},"td_356x220":{"file":"banner-colheita-milho-356x180.jpg","width":356,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-356x180.jpg"},"td_356x364":{"file":"banner-colheita-milho-356x180.jpg","width":356,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-356x180.jpg"},"td_533x261":{"file":"banner-colheita-milho-533x180.jpg","width":533,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-533x180.jpg"},"td_534x462":{"file":"banner-colheita-milho-534x180.jpg","width":534,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-534x180.jpg"},"td_696x385":{"file":"banner-colheita-milho-696x180.jpg","width":696,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-696x180.jpg"},"td_741x486":{"file":"banner-colheita-milho-741x180.jpg","width":741,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho-741x180.jpg"},"full":{"file":"banner-colheita-milho.jpg","width":900,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":833,"source_url":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-content\/uploads\/2020\/12\/banner-colheita-milho.jpg","_links":{"self":[{"href":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-json\/wp\/v2\/media\/841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sementesbiomatrix.com.br\/blog\/wp-json\/wp\/v2\/comments?post=841"}]}}